{"id":945,"date":"2009-10-28T15:14:18","date_gmt":"2009-10-28T15:14:18","guid":{"rendered":"https:\/\/christophethibierge.com\/blogthib\/?p=945"},"modified":"2009-10-28T15:14:18","modified_gmt":"2009-10-28T15:14:18","slug":"linux-ubuntu-intro","status":"publish","type":"post","link":"https:\/\/christophethibierge.com\/blogthib\/2009\/10\/28\/linux-ubuntu-intro\/","title":{"rendered":"Linux Ubuntu &#8211; intro"},"content":{"rendered":"<p>Ceci est un premier point d&rsquo;\u00e9tape de ma vie avec Linux (Ubuntu 9.04 \u00e0 ce jour). Ce syst\u00e8me d&rsquo;exploitation est install\u00e9 en double boot sur mon portable, en cohabitation avec Windows Vista. Je pr\u00e9vois de r\u00e9diger quelques Thibillets sp\u00e9cifiquement d\u00e9di\u00e9s \u00e0 Linux Ubuntu (\u00e0 ne pas confondre avec ma liste de Ubuntus, c&rsquo;est-\u00e0-dire les petits bonheurs au quotidien, <a href=\"https:\/\/christophethibierge.com\/blogthib\/index.php\/Ubuntu\">dans la rubrique du m\u00eame nom<\/a>).<\/p>\n<p> Voici quelques raisons pour l&rsquo;ouverture d&rsquo;une nouvelle rubrique sp\u00e9cifique Linux Ubuntu : <\/p>\n<ul>\n<li>Conserver la m\u00e9moire de mes installations, interrogations&#8230; et solutions. Et le blog, y a rien de mieux pour \u00e7a.<\/li>\n<li>Pointer vers des ressources que j&rsquo;ai identifi\u00e9es apr\u00e8s recherche (on ne sait jamais, je ne suis pas le seul \u00e0 <em>switcher<\/em>).<\/li>\n<li>Partager mon point de vue ou poser des questions ouvertes.<\/li>\n<\/ul>\n<p> Nous commen\u00e7ons avec quelques remarques g\u00e9n\u00e9rales sur cette installation et ma premi\u00e8re semaine avec Ubuntu : <\/p>\n<ul>\n<li>Si je suis pass\u00e9 de Vista \u00e0 Ubuntu, c&rsquo;est parce que <strong>je n&rsquo;en pouvais plus du temps de d\u00e9marrage de Windows<\/strong> avant \u00ab\u00a0d&rsquo;avoir la main\u00a0\u00bb (on est pass\u00e9 \u00e0 <a href=\"https:\/\/christophethibierge.com\/blogthib\/2009\/10\/19\/948-ubuntu-ubuntu\">3mn53<\/a>). Cela \u00e9tait aussi valable pour <strong>la sortie de veille<\/strong> : sous Mac, celle-ci est quasiment instantan\u00e9e ; sous Ubuntu, idem. Sous Windows, on sent que la disquette 5&Prime;1\/4 tourne dans le vide avant que \u00e7a commence \u00e0 r\u00e9agir : \u00e0 part ma lointaine \u00e9poque o\u00f9 je jouais au tennis sous Pong, je me lasse vite des curseurs qui clignotent&#8230; Bref, je suis content : comme pour tous les OS, Ubuntu rame un peu \u00e0 r\u00e9tablir la connexion wifi, mais il s&rsquo;agit d&rsquo;une poign\u00e9e de secondes, le reste est imm\u00e9diatement op\u00e9rationnel. <strong>En fait, Ubuntu c&rsquo;est le Mac du geek<\/strong>.<\/li>\n<li>En installant et en param\u00e9trant Ubuntu, <strong>je me f\u00e9licite d&rsquo;avoir op\u00e9r\u00e9 il y a quelques ann\u00e9es le double-virage \u00ab\u00a0logiciels libres\u00a0\u00bb et \u00ab\u00a0bureau sur Internet\u00a0\u00bb<\/strong>. Logiciels libres, parce que mes outils au quotidien tournent sur les 3 OS : Firefox, Thunderbird, Sunbird, OpenOffice sont les outils que j&rsquo;utilise quel que soit l&rsquo;OS sur lequel je travaille. Je retrouve les m\u00eames extensions, les m\u00eames raccourcis, donc un gain de confort appr\u00e9ciable \u00e0 l&rsquo;installation. Bureau sur Internet, parce que je veux pouvoir consulter mes ressources depuis n&rsquo;importe quel ordinateur. J&rsquo;utilise donc Netvibes comme page d&rsquo;accueil de navigateur, et toutes mes r\u00e9flexions, mes liens, mes sondages et fils RSS sont consultables en ligne ; et je partage mes Bookmarks en ligne avec Startaid, ce qui me permet d&rsquo;avoir mes signets \u00e0 jour quel que soit le syst\u00e8me sur lequel je travaille.<\/li>\n<li>Je suis tr\u00e8s agr\u00e9ablement surpris par l&rsquo;ergonomie et la facilit\u00e9 d&rsquo;installation. Un exemple parmi tant d&rsquo;autres : pour installer mon imprimante HP (en wifi), j&rsquo;ai fait Syst\u00e8me, Administration, Impression, et j&rsquo;ai fait \u00ab\u00a0nouvelle imprimante\u00a0\u00bb. Ubuntu l&rsquo;a d\u00e9tect\u00e9e en wifi, et l&rsquo;a install\u00e9e, <strong>sans red\u00e9marrage ou processus long d&rsquo;installation<\/strong>. Sous Windows, il faut ins\u00e9rer un CD, installer 200 megas de pilotes et logiciels (10-15 mn), et red\u00e9marrer tout le syst\u00e8me (\u00e0 3mn53 le red\u00e9marrage). <strong>Comble de l&rsquo;humour<\/strong> : pour installer une imprimante wifi, il faut la connecter d&rsquo;abord avec un cable USB ; \u00e7a ne va pas nous pousser \u00e0 avoir moins de c\u00e2bles&#8230; Sans parler du petit logiciel espion de mise \u00e0 jour que l&rsquo;on ne peut pas d\u00e9sactiver (et qui ralentit le d\u00e9marrage), des fen\u00eatres \u00ab\u00a0votre imprimante est pass\u00e9e en veille\u00a0\u00bb \/ \u00ab\u00a0votre imprimante est d\u00e9connect\u00e9e\u00a0\u00bb et autres interruptions quotidiennes&#8230;<\/li>\n<\/ul>\n<p> Alors certes, il n&rsquo;y a pas d&rsquo;aussi jolies images que sous Vista ou Mac OS, mais je souhaite revenir pour l&rsquo;instant \u00e0 <strong>un environnement de travail<\/strong>, rapide et efficace. Nous verrons combien de temps je tiens ce discours optimiste \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ceci est un premier point d&rsquo;\u00e9tape de ma vie avec Linux (Ubuntu 9.04 \u00e0 ce jour). Ce syst\u00e8me d&rsquo;exploitation est install\u00e9 en double boot sur mon portable, en cohabitation avec Windows Vista. Je pr\u00e9vois de r\u00e9diger quelques Thibillets sp\u00e9cifiquement d\u00e9di\u00e9s &hellip; <a href=\"https:\/\/christophethibierge.com\/blogthib\/2009\/10\/28\/linux-ubuntu-intro\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-945","post","type-post","status-publish","format-standard","hentry","category-informatique-et-internet"],"_links":{"self":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/comments?post=945"}],"version-history":[{"count":0,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/945\/revisions"}],"wp:attachment":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/media?parent=945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/categories?post=945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/tags?post=945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}