{"id":825,"date":"2008-11-25T23:10:39","date_gmt":"2008-11-25T23:10:39","guid":{"rendered":"https:\/\/christophethibierge.com\/blogthib\/?p=825"},"modified":"2008-11-25T23:10:39","modified_gmt":"2008-11-25T23:10:39","slug":"caillou-zone-photonique","status":"publish","type":"post","link":"https:\/\/christophethibierge.com\/blogthib\/2008\/11\/25\/caillou-zone-photonique\/","title":{"rendered":"Caillou &#8211; Zone photonique"},"content":{"rendered":"<blockquote><p>la banlieue est comme un grenier<br \/>\n Gris et indistinct<br \/>\n D&rsquo;objets amoncel\u00e9s.<br \/>\n Il suffit d&rsquo;un rayon de soleil<br \/>\n Comme une lampe-torche<br \/>\n Pour faire briller les choses.<\/p>\n<p> Et l\u00e0,<br \/>\n Poussi\u00e8re d&rsquo;\u00e9tincelles<br \/>\n Soudainement.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>la banlieue est comme un grenier Gris et indistinct D&rsquo;objets amoncel\u00e9s. Il suffit d&rsquo;un rayon de soleil Comme une lampe-torche Pour faire briller les choses. Et l\u00e0, Poussi\u00e8re d&rsquo;\u00e9tincelles Soudainement.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-825","post","type-post","status-publish","format-standard","hentry","category-caillou"],"_links":{"self":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":0,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"wp:attachment":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}