{"id":699,"date":"2008-06-12T19:52:39","date_gmt":"2008-06-12T19:52:39","guid":{"rendered":"https:\/\/christophethibierge.com\/blogthib\/?p=699"},"modified":"2008-06-12T19:52:39","modified_gmt":"2008-06-12T19:52:39","slug":"aragog-et-magog","status":"publish","type":"post","link":"https:\/\/christophethibierge.com\/blogthib\/2008\/06\/12\/aragog-et-magog\/","title":{"rendered":"Aragog et Magog"},"content":{"rendered":"<p>Hier matin, dans le train, dans la torpeur de l&rsquo;aube. J&rsquo;entends un cri, un remue-m\u00e9nage, d&rsquo;autres cris. Plusieurs passagers refluent du compartiment du bas, ils fuient. Encore du remue-m\u00e9nage, on ne comprend rien, j&rsquo;aper\u00e7ois juste une dame qui se tr\u00e9mousse en criant. <br \/> Et puis le mot passe : c&rsquo;\u00e9tait une araign\u00e9e. Pas grosse, en plus, mais il y a des peurs qui ne se commandent pas.<br \/> Plusieurs personnes rient, commentent, y vont de leur bon mot. Je souris, mais je ne trouve pas la situation amusante : il y a trop de personnes qui ont commenc\u00e9 par s&rsquo;\u00e9carter, et fuir, avant m\u00eame d&rsquo;essayer de comprendre. <br \/>Une foule peut annuler 10 000 ann\u00e9es de d\u00e9veloppement du cerveau. Et ce que j&rsquo;ai vu l\u00e0, c&rsquo;est vraiment la mauvaise part de l&rsquo;homme. C&rsquo;est une combinaison d&rsquo;instinct gr\u00e9gaire issu du Pr\u00e9cambrien, mais aussi de r\u00e9flexes int\u00e9gr\u00e9s tr\u00e8s r\u00e9cemment : individualisme, fuite devant l&rsquo;incompr\u00e9hensible, absence d&#8217;empathie, chacun pour soi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier matin, dans le train, dans la torpeur de l&rsquo;aube. J&rsquo;entends un cri, un remue-m\u00e9nage, d&rsquo;autres cris. Plusieurs passagers refluent du compartiment du bas, ils fuient. Encore du remue-m\u00e9nage, on ne comprend rien, j&rsquo;aper\u00e7ois juste une dame qui se tr\u00e9mousse &hellip; <a href=\"https:\/\/christophethibierge.com\/blogthib\/2008\/06\/12\/aragog-et-magog\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-699","post","type-post","status-publish","format-standard","hentry","category-reflexions"],"_links":{"self":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/comments?post=699"}],"version-history":[{"count":0,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/699\/revisions"}],"wp:attachment":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/media?parent=699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/categories?post=699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/tags?post=699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}