{"id":665,"date":"2008-05-06T22:42:30","date_gmt":"2008-05-06T22:42:30","guid":{"rendered":"https:\/\/christophethibierge.com\/blogthib\/?p=665"},"modified":"2026-01-02T12:56:54","modified_gmt":"2026-01-02T11:56:54","slug":"epistemologie-ontologique-du-sabre-laser","status":"publish","type":"post","link":"https:\/\/christophethibierge.com\/blogthib\/2008\/05\/06\/epistemologie-ontologique-du-sabre-laser\/","title":{"rendered":"Epist\u00e9mologie ontologique du sabre laser"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/arme_sabre_anakin_03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"642\" src=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/arme_sabre_anakin_03.jpg\" alt=\"\" class=\"wp-image-6997\" style=\"width:278px;height:auto\" srcset=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/arme_sabre_anakin_03.jpg 500w, https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/arme_sabre_anakin_03-234x300.jpg 234w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Quand mon grand-p\u00e8re avait vu \u00ab\u00a0la guerre des \u00e9toiles\u00a0\u00bb (on ne disait pas encore Staroirz), d\u00e8s le d\u00e9but (attaque du vaisseau diplomatique de la Princesse Le\u00efa par les forces de l&rsquo;Empire), il avait tiqu\u00e9. <br> On voyait des braves soldats se faire d\u00e9zinguer \u00e0 coups de pistolasers, et \u00e7a faisait Piou Piou tandis que des \u00e9clairs lumineux et brefs jaillissaient de la bouche fumante des pistolasers.<br> Mon grand-p\u00e8re, qui n&rsquo;\u00e9tait pas Polytechnicien pour rien : \u00ab\u00a0Ce ne sont pas des pistolasers ! Un laser, c&rsquo;est comme une lampe-torche, tu l&rsquo;allumes et la lumi\u00e8re en sort, et si on n&rsquo;\u00e9teint pas, le faisceau lumineux s&rsquo;allonge sans rupture. L\u00e0, ce sont des balles tra\u00e7antes.\u00a0\u00bb<br> Mon grand-p\u00e8re avait laiss\u00e9 son me d&rsquo;enfant quelque part, il raisonnait en froid polytechnicien. Personne n&rsquo;est parfait.<br> D&rsquo;o\u00f9 mon interrogation du jour, dont la profondeur \u00e9gale <a href=\"http:\/\/www.autolargue.net\/\">la question sur le demi-tour d&rsquo;Actarus dans Goldorak<\/a> :<\/p>\n\n\n\n<p><span style=\"font-weight: bold;\">Comment fonctionne un sabre laser ?<\/span><\/p>\n\n\n\n<p> <span style=\"font-weight: bold;\">Prol\u00e9gom\u00e8ne : <\/span><br> un sabre laser produit un laser qui  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>est limit\u00e9 en hauteur<\/li>\n\n\n\n<li>est analogue \u00e0 une \u00e9p\u00e9e, qui peut couper de taille (avec son tranchant) ou d&rsquo;estoc (avec sa pointe). Par exemple, quand Krung Grop Tep, le mentor d&rsquo;Obi Wan, se fait trouer par Dark Maul, c&rsquo;est un coup d&rsquo;estoc.<\/li>\n<\/ul>\n\n\n\n<p><strong>Interrogation suite au prol\u00e9gom\u00e8ne :<\/strong><\/p>\n\n\n\n<p>Un vrai laser, version 2008, et pas version \u00ab\u00a0il y a tr\u00e8s tr\u00e8s longtemps, dans une galaxie tr\u00e8s tr\u00e8s lointaine\u00a0\u00bb, est un rayon lumineux qui troue et coupe, mais qui n&rsquo;est pas limit\u00e9 en longueur. Donc ma question, c&rsquo;est \u00ab\u00a0qu&rsquo;est-ce qui stoppe le laser du sabre laser \u00e0 1m20 du fourreau pour lui donner cette ergonomie d&rsquo;\u00e9p\u00e9e arch\u00e9o-futuriste ?\u00a0\u00bb<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><a href=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/Sabretooth.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"158\" height=\"441\" src=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/Sabretooth.jpg\" alt=\"\" class=\"wp-image-6999\" srcset=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/Sabretooth.jpg 158w, https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/Sabretooth-107x300.jpg 107w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>La premi\u00e8re id\u00e9e est : un miroir. J&rsquo;y ai beaucoup r\u00e9fl\u00e9chi dans le m\u00e9tro, et j&rsquo;aboutis au dessin ci-joint. Alors tu vois, le manche bleu p\u00e2le, c&rsquo;est le manche, celui qu&rsquo;on tient \u00e0 la main et que R2D2 envoie \u00e0 Luke dans \u00ab\u00a0Le retour du Jedi\u00a0\u00bb pour abattre l&rsquo;infme Jabba. On pousse sur un bouton, et hop, le g\u00e9n\u00e9rateur de laser (carr\u00e9 rouge) envoie le laser (trait rouge). Ce laser passe \u00e0 travers un miroir sans tain (noir pointill\u00e9) et va taper dans un miroir (noir plein), hop, le laser bondit vers le haut, et \u00e0 1m20 de hauteur, un autre miroir biface d\u00e9complex\u00e9 (triangle noir en haut) renvoie le laser vers le bas, ad vitam aeternam. Ainsi, on a un laser limit\u00e9 en longueur, mais qui coupe bien, avec en plus un raffinement : plus le sabre laser est allum\u00e9 longtemps, plus le rayon est concentr\u00e9 (multiplication des allers-retours), plus il est puissant. On pourrait appeler \u00e7a \u00ab\u00a0La concentration de pr\u00e9chauffe de Thibierge\u00a0\u00bb, en toute modestie.<\/p>\n\n\n\n<p>Mais argh, je ne serai jamais prix Nobel :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Il n&rsquo;y a pas de miroir en haut (ou alors, on ne voit pas comment il tiendrait tout seul dans l&rsquo;air)<\/li>\n\n\n\n<li>Si on se d\u00e9brouillait pour en installer un (\u00ab\u00a0on dirait que quand on allume le sabre, un miroir se mat\u00e9rialise en haut\u00a0\u00bb), il n&rsquo;y aurait plus d&rsquo;effet d&rsquo;estoc, et Krup Gong Couic n&rsquo;aurait pas pu \u00eatre trou\u00e9 par Dark Maul.<\/li>\n<\/ol>\n\n\n\n<p>Nous voil\u00e0 &#8211; presque &#8211; revenus au point de d\u00e9part. Et l\u00e0, j&rsquo;ai une id\u00e9e, mais j&rsquo;ai besoin de physiciens, \u00e9ventuellement &lsquo;Pataphysiciens, ce serait plus fun. On va dire qu&rsquo;il y a un champ de force qui est cr\u00e9\u00e9 quand on allume le sabre, et que c&rsquo;est ce champ de force qui repousse le laser \u00e0 partir de 1m20, jouant le r\u00f4le du miroir distant. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/FieldCastro.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"136\" height=\"230\" src=\"https:\/\/christophethibierge.com\/blogthib\/wp-content\/uploads\/2008\/05\/FieldCastro.jpg\" alt=\"\" class=\"wp-image-7000\"\/><\/a><\/figure>\n<\/div>\n\n\n<p><br> Cf. la figure suivante, o\u00f9 le champ de force &#8211; appelons-le \u00ab\u00a0Field Castro\u00a0\u00bb &#8211; est figur\u00e9 sous forme d&rsquo;un mignon nuage moutarde. Mais reste le probl\u00e8me de l&rsquo;estoc : un champ de force capable de repousser un laser, il ne va pas permettre de toucher son ennemi, le dit ennemi sera lui-m\u00eame expuls\u00e9 de la zone de combat par le champ de force (effet blocus de Field Castro). <br><\/p>\n\n\n\n<p>Je ne m&rsquo;en sors plus. Des id\u00e9es, quelqu&rsquo;un(e) ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand mon grand-p\u00e8re avait vu \u00ab\u00a0la guerre des \u00e9toiles\u00a0\u00bb (on ne disait pas encore Staroirz), d\u00e8s le d\u00e9but (attaque du vaisseau diplomatique de la Princesse Le\u00efa par les forces de l&rsquo;Empire), il avait tiqu\u00e9. On voyait des braves soldats se &hellip; <a href=\"https:\/\/christophethibierge.com\/blogthib\/2008\/05\/06\/epistemologie-ontologique-du-sabre-laser\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-665","post","type-post","status-publish","format-standard","hentry","category-reflexions"],"_links":{"self":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":1,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/665\/revisions"}],"predecessor-version":[{"id":7001,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/665\/revisions\/7001"}],"wp:attachment":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/categories?post=665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/tags?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}