{"id":62,"date":"2006-04-05T20:11:36","date_gmt":"2006-04-05T20:11:36","guid":{"rendered":"https:\/\/christophethibierge.com\/blogthib\/?p=62"},"modified":"2006-04-05T20:11:36","modified_gmt":"2006-04-05T20:11:36","slug":"le-destin-est-une-valise-a-roulettes","status":"publish","type":"post","link":"https:\/\/christophethibierge.com\/blogthib\/2006\/04\/05\/le-destin-est-une-valise-a-roulettes\/","title":{"rendered":"Le Destin est une valise \u00e0 roulettes"},"content":{"rendered":"<p>Dans l&rsquo;enceinte de la Gare Saint-Lazare, la lutte est rude. Il y a du monde, certes, comme dans le m\u00e9tro, mais ce monde est <em>en mouvement<\/em>. Normalement, les conditions id\u00e9ales de nos soci\u00e9t\u00e9s modernes sont : <\/p>\n<ul>\n<li>soit il y a du monde, beaucoup de monde, mais il n&rsquo;y quasiment pas de mouvement (exemple : une rame de m\u00e9tro), de telle sorte que se cr\u00e9e une forme de coh\u00e9sion cristallographique, chacun s&rsquo;ajuste par rapport aux autres, cr\u00e9e des liaisons de covalence, bref, se place sur la grille atomique. La rame de m\u00e9tro devient une mol\u00e9cule complexe, form\u00e9e d&rsquo;atomes humains. Et comme une mol\u00e9cule, celle-ci est relativement fig\u00e9e, donc solide, jusqu&rsquo;\u00e0 ce qu&rsquo;une forte temp\u00e9rature (incendie, canicule) d\u00e9solidarise les atomes-usagers en une fuite d\u00e9sordonn\u00e9e vers les issues de secours ou les terrasses de caf\u00e9s.<\/li>\n<li>soit il y a peu de monde, et beaucoup d&rsquo;espace, ce qui permet de se propulser selon des trajectoires rectilignes (exemple : les all\u00e9es d&rsquo;un supermarch\u00e9 un jour de semaine, l&rsquo;esplanade du Trocad\u00e9ro, la Place Rouge), chacun est un petit atome de gaz dont on ne saurait pr\u00e9dire en m\u00eame temps la trajectoire et la vitesse, mais on s&rsquo;en fout, car il n&rsquo;y a pas de risque de collision (rappel : l&rsquo;espace est grand)<\/li>\n<\/ul>\n<p> A ces deux situations \u00e9quilibr\u00e9es, correspondent <em>mutatis mutandis<\/em><\/p>\n<ul>\n<li>l&rsquo;espace grand, avec des personnes immobiles (exemple : une plage des landes \u00e0 10 h du matin en juin), qui correspond \u00e0 une situation <em>absolument inint\u00e9ressante<\/em> \u00e0 tout point de vue. <\/li>\n<li>l&rsquo;espace bond\u00e9 de personnes en mouvement (exemple : la Gare Saint Lazare), l&rsquo;extr\u00eame de notre entropie urbaine, le test ultime de m\u00e9canique des fluides.<\/li>\n<\/ul>\n<p> C&rsquo;est cette derni\u00e8re situation qui m&rsquo;int\u00e9resse, car les Parques ne sont jamais l\u00e0 o\u00f9 on les attend. Imaginons la sc\u00e8ne : une meute d&rsquo;usag\u00e9s se faufile, se chevauche, s&rsquo;entrem\u00eale dans une qu\u00eate fr\u00e9n\u00e9tique de rapidit\u00e9. Compte-tenu de la forte densit\u00e9 humaine au m\u00e8tre carr\u00e9, le faible taux de collision est \u00e9tonnant, et montre l&rsquo;efficience de ce type de syst\u00e8me. L&rsquo;usag\u00e9 moyen est rapide, r\u00e9actif, attentif, souple, il change de direction comme de chemise, \u00e9vite, contourne, circonvient, tout en se payant le luxe d&rsquo;arborer une expression tristement neutre, fatigu\u00e9e, ou lointaine (d\u00e9volue aux \u00e9couteurs de wok-man). C&rsquo;est merveille de voir comme 100 000 ans d&rsquo;humanit\u00e9 et 8 000 ans de civilisation aboutissent \u00e0 cette perfection soci\u00e9tale.<\/p>\n<p> Je ne d\u00e9roge pas \u00e0 la r\u00e8gle, je l&rsquo;avoue, je m&rsquo;immerge avec d\u00e9lices dans ce magma gluant de sueur et de d\u00e9cibels, et, tel la fourmi de course moyenne, j&rsquo;occupe chaque brin d&rsquo;espace que me laissent les autres lobotomis\u00e9s. Mais malheur \u00e0 ceux qui se croient plus forts que le syst\u00e8me. Des intr\u00e9pides, acrobates ou yamakasi, bref, des <em>risk-lovers<\/em> se la jouent \u00ab\u00a0hip-hop, je vais plus vite que les autres, je fr\u00f4le au plus pr\u00e8s, je suis comme une mobylette de livreur de pizzas zig-zaguant entre des voitures diesel\u00a0\u00bb. Mais comme dit la pub de la s\u00e9curit\u00e9 routi\u00e8re sur les motards : <em>agiles, mais fragiles<\/em>.<\/p>\n<p> Voici notre protagoniste. Une expression populaire, souvent pratiqu\u00e9e par ma tante, est <em>Con comme une valise<\/em>. Il n&rsquo;y a pas plus vrai. Dans les diff\u00e9rentes esp\u00e8ces de valise (valise en carton, valise sous les yeux, valise pleine de schnouf ou de biftons), la valise \u00e0 roulette tient le pompon. D\u00e9composons l&rsquo;approche en quelques axiomes et leurs corollaires :<\/p>\n<ol>\n<li>espace restreint, gens nombreux, tous en d\u00e9placement<\/li>\n<li>jeunes livreurs de pizza v\u00e9loces, qui se faufilent au plus juste entre les usag\u00e9s<\/li>\n<li>mobiles, alertes, mais ne regardant qu&rsquo;\u00e0 hauteur des yeux, pour rep\u00e9rer la faille entre deux quidams (ou qui-dames)<\/li>\n<li>donc ne regardant pas leurs pieds<\/li>\n<li>et (je me r\u00e9p\u00e8te) fr\u00f4lant au plus juste les p\u00e9kins de la foule magmateuse<\/li>\n<li>SCHLAKK ! Tr\u00e9buchement sur valise \u00e0 roulette con tir\u00e9e telle une vache asthmatique par une sympathique rombi\u00e8re qui n&rsquo;a pas invent\u00e9 la machine \u00e0 cambrer les bananes<\/li>\n<\/ol>\n<p> La valise \u00e0 roulettes fauche en pleine v\u00e9locit\u00e9 celui qui croyait \u00e9voluer dans un monde d&rsquo;obstacles verticaux (ses fr\u00e8res humains) tous proches les uns des autres. La valise \u00e0 roulettes, c&rsquo;est le crocheur de pattes horizontal, l&rsquo;animal \u00e0 l&rsquo;aff\u00fbt, le voisin de palier qui vous a secr\u00e8tement jalous\u00e9 pendant 10 ans, et qui a renvers\u00e9 expr\u00e8s de l&rsquo;huile d&rsquo;olive dans l&rsquo;escalier. La valise \u00e0 roulettes, c&rsquo;est la figure s\u00e9culaire du Destin qui nous explique \u00e0 tous que, on a beau se croire jeune, intouchable et immarscecible, viendra toujours le moment o\u00f9 l&rsquo;on explosera en vol. Voil\u00e0 ce qu&rsquo;il en co\u00fbte, de se croire infini.<\/p>\n<p> PS : <a href=\"http:\/\/www.parismarathon.com\/\" >J-4<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans l&rsquo;enceinte de la Gare Saint-Lazare, la lutte est rude. Il y a du monde, certes, comme dans le m\u00e9tro, mais ce monde est en mouvement. Normalement, les conditions id\u00e9ales de nos soci\u00e9t\u00e9s modernes sont : soit il y a du monde, beaucoup de monde, mais il n&rsquo;y quasiment pas de mouvement (exemple : une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[84],"class_list":["post-62","post","type-post","status-publish","format-standard","hentry","category-reflexions","tag-reflexions"],"_links":{"self":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/comments?post=62"}],"version-history":[{"count":0,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/posts\/62\/revisions"}],"wp:attachment":[{"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/media?parent=62"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/categories?post=62"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/christophethibierge.com\/blogthib\/wp-json\/wp\/v2\/tags?post=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}